{"id":30248,"date":"2025-10-15T09:01:53","date_gmt":"2025-10-15T09:01:53","guid":{"rendered":"https:\/\/kmdonu.com\/?post_type=product&#038;p=30248"},"modified":"2025-10-15T09:01:53","modified_gmt":"2025-10-15T09:01:53","slug":"used-onu-gpon-epon-hg6201m-2-4g-wifi","status":"publish","type":"product","link":"https:\/\/kmdonu.com\/pt\/produto\/used-onu-gpon-epon-hg6201m-2-4g-wifi\/","title":{"rendered":"USED ONU GPON EPON HG6201M 2.4G WIFI"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-30249\" src=\"https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-300x300.jpg 300w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-800x800.jpg 800w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-150x150.jpg 150w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-768x768.jpg 768w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-12x12.jpg 12w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-430x430.jpg 430w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-700x700.jpg 700w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-30250\" src=\"https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-3-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-3-300x300.png 300w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-3-150x150.png 150w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-3-768x768.png 768w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-3-12x12.png 12w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-3-430x430.png 430w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-3-700x700.png 700w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/1-3.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-30251\" src=\"https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/2-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/2-300x300.jpg 300w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/2-800x800.jpg 800w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/2-150x150.jpg 150w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/2-768x768.jpg 768w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/2-12x12.jpg 12w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/2-430x430.jpg 430w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/2-700x700.jpg 700w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/2.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-30252\" src=\"https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/\u9644\u56fe1-1-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/\u9644\u56fe1-1-300x300.png 300w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/\u9644\u56fe1-1-150x150.png 150w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/\u9644\u56fe1-1-768x768.png 768w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/\u9644\u56fe1-1-12x12.png 12w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/\u9644\u56fe1-1-430x430.png 430w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/\u9644\u56fe1-1-700x700.png 700w, https:\/\/kmdonu.com\/wp-content\/uploads\/2025\/10\/\u9644\u56fe1-1.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<h1 title=\"USED GPON ONU HG6201M 2.4G Single Band WIFI English Firmware EPON GPON ONU ONT WIFI Router for Optical Fiber Network\" data-spm-anchor-id=\"a2700.details.0.i68.736f5a79e7gOaF\">USED GPON ONU HG6201M 2.4G Single Band WIFI English Firmware EPON GPON ONU ONT WIFI Router for Optical Fiber Network<\/h1>","protected":false},"featured_media":30251,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[86],"product_tag":[],"class_list":{"0":"post-30248","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-single-band","8":"first","9":"instock","10":"sale","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/product\/30248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/comments?post=30248"}],"version-history":[{"count":1,"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/product\/30248\/revisions"}],"predecessor-version":[{"id":30253,"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/product\/30248\/revisions\/30253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/media\/30251"}],"wp:attachment":[{"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/media?parent=30248"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/product_brand?post=30248"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/product_cat?post=30248"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kmdonu.com\/pt\/wp-json\/wp\/v2\/product_tag?post=30248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}